{"id":3318,"date":"2024-11-12T12:04:35","date_gmt":"2024-11-12T12:04:35","guid":{"rendered":"https:\/\/testsystem.medicine-beauty.ch\/liposuccion\/"},"modified":"2024-12-12T11:27:35","modified_gmt":"2024-12-12T11:27:35","slug":"liposuccion","status":"publish","type":"page","link":"https:\/\/medicine-beauty.ch\/fr\/liposuccion\/","title":{"rendered":"Liposuc\u00adcion"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3318\" class=\"elementor elementor-3318 elementor-3095\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59c2c1c elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"59c2c1c\" data-element_type=\"section\" data-e-type=\"section\" id=\"top-section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab82478\" data-id=\"ab82478\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb814a9 elementor-widget elementor-widget-heading\" data-id=\"bb814a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Liposuc\u00adcion<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-492cf9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"492cf9b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87bc991\" data-id=\"87bc991\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96d27cb animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"96d27cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Infor\u00adma\u00adti\u00adons sur la liposuccion<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5ff45a elementor-widget elementor-widget-text-editor\" data-id=\"c5ff45a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bien que l'on puisse et doive influen\u00adcer consid\u00e9\u00adra\u00adblem\u00adent sa silhou\u00adette par l'alimentation et le sport, il existe des<strong> zones \u00e0&nbsp;probl\u00e8mes typiques<\/strong> qui ne peuvent \u00eatre suffi\u00adsam\u00adment influen\u00adc\u00e9es <strong>ni par des mesures di\u00e9t\u00e9\u00adti\u00adques, ni par un entra\u00ee\u00adne\u00adment intensif<\/strong>. (par exemple : taille\/\u200bhanches, int\u00e9rieur des cuisses, fesses, ventre, culotte de cheval, int\u00e9rieur des genoux, bras, menton,&nbsp;cou).&nbsp;<\/p>\n<p>Nous avons une structure corpo\u00adrelle et une silhou\u00adette g\u00e9n\u00e9ti\u00adquement d\u00e9ter\u00admi\u00adn\u00e9es - et nous ne pouvons malheu\u00adreu\u00adse\u00adment pas contr\u00f4ler les endroits o\u00f9 le corps doit \"fondre\" lorsque nous perdons du poids. Et c'est pr\u00e9cis\u00ad\u00e9\u00adment pour <u>ces<\/u> parties du corps que la <strong>liposuc\u00adcion est la technique optimale<\/strong>. La liposuc\u00adcion n'est pas un traite\u00adment de l'ob\u00e9sit\u00e9 ; cependant, utilis\u00e9e initia\u00adle\u00adment et en parti\u00adcu\u00adlier en combi\u00adnai\u00adson avec une alimen\u00adta\u00adtion \u00e9quili\u00adbr\u00e9e, une influence m\u00e9dica\u00admen\u00adteuse (par ex. les nouveaux agonistes GLP-1 (injec\u00adtions amaigris\u00adsan\u00adtes) comme \"Ozempic\", \"Wegovy\", \"Munjaro\" etc. et suffi\u00adsam\u00adment d'exercice physique, elle peut apporter une excel\u00adlente am\u00e9lio\u00adra\u00adtion des contours et optimiser l'image corpo\u00adrelle. Vous vous sentirez<strong> beaucoup plus \u00e0&nbsp;l'aise avec votre nouvelle silhou\u00adette<\/strong>.   <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6995c47 elementor-align-center animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"6995c47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontaktformular\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demander mainten\u00adant  <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55cf6ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55cf6ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bb871b0\" data-id=\"bb871b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f664ba animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3f664ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_tablet&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-anzeichnen.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI0NSwidXJsIjoiaHR0cHM6XC9cL21lZGljaW5lLWJlYXV0eS5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTFcL2RyLXBldGVyLWRpZXR6LWZldHRhYnNhdWd1bmctYW56ZWljaG5lbi5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"450\" src=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-anzeichnen.jpg\" class=\"attachment-large size-large wp-image-3245\" alt=\"dr-peter-dietz-fettabsaugung-anzeichnen\" srcset=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-anzeichnen.jpg 650w, https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-anzeichnen-300x208.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-738b89e\" data-id=\"738b89e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6718fd animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"a6718fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-op.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzIzOSwidXJsIjoiaHR0cHM6XC9cL21lZGljaW5lLWJlYXV0eS5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTFcL2RyLXBldGVyLWRpZXR6LWZldHRhYnNhdWd1bmctb3AuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"650\" height=\"450\" src=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-op.jpg\" class=\"attachment-large size-large wp-image-3239\" alt=\"dr-peter-dietz-fettabsaugung-op\" srcset=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-op.jpg 650w, https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-op-300x208.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d015560\" data-id=\"d015560\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e35f2f2 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e35f2f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_tablet&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-operation.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI0MiwidXJsIjoiaHR0cHM6XC9cL21lZGljaW5lLWJlYXV0eS5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTFcL2RyLXBldGVyLWRpZXR6LWZldHRhYnNhdWd1bmctb3BlcmF0aW9uLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"650\" height=\"450\" src=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-operation.jpg\" class=\"attachment-large size-large wp-image-3242\" alt=\"dr-peter-dietz-fettabsaugung-operation\" srcset=\"https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-operation.jpg 650w, https:\/\/medicine-beauty.ch\/wp-content\/uploads\/2024\/11\/dr-peter-dietz-fettabsaugung-operation-300x208.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e674622 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e674622\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74afbdf\" data-id=\"74afbdf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f322d4c animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f322d4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Liposuc\u00adcion - l'essentiel en&nbsp;bref<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60981fc elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"60981fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg id=\"uuid-b003a3b2-6660-4321-914e-09565e94dca5\" viewBox=\"0 0 137.04 86.98\"><path d=\"M71.97,86.98c1.14-2.65,2.32-5.23,3.36-7.86,1.14-2.86,1.96-5.81,2.37-8.89.5-3.79-.89-6.68-3.83-8.95-3.32-2.58-6.93-4.7-10.63-6.69-.19-.1-.58-.08-.75.05-3.2,2.41-6.44,4.77-9.55,7.29-1.45,1.18-2.62,2.7-3.94,4.05-2.31,2.38-4.61,4.77-6.97,7.1-3.97,3.95-8.88,6.19-14.29,7.18-8.38,1.53-15.85-.67-22.24-6.26C.11,69.29-1.51,61.47,1.49,54.62c.93-2.12,2.3-4.04,3.52-6.02.19-.3.58-.55.93-.68,5.89-2.13,11.79-4.24,17.69-6.35.07-.03.15-.04.34.07-.24.21-.48.41-.7.64-2.86,2.83-5.47,5.87-7.19,9.55-1.29,2.75-2,5.61-1.15,8.64,1,3.54,3.54,5.67,6.81,6.95,4.19,1.64,8.48,1.32,12.75.27,4.54-1.11,8.57-3.37,12.49-5.82,4.28-2.67,8.32-5.69,12.16-8.96.12-.1.26-.18.41-.29-.15-.12-.2-.17-.27-.21-8.16-4.07-16.06-8.65-24.64-11.84-2.95-1.1-5.91-2.22-8.81-3.45-1.46-.62-2.85-1.42-4.18-2.28-4.26-2.74-5.79-6.8-5.39-11.69.54-6.57,4.15-11.32,9.17-15.18,5.12-3.93,10.85-6.52,17.26-7.47,4.84-.72,9.7-.94,14.33,1.06,4.71,2.03,8.17,5.31,9.48,10.44.86,3.37.13,6.56-1.39,9.63-1.87,3.79-4.91,6.48-8.23,8.92-1.17.86-2.39,1.67-3.65,2.55.21.13.37.24.54.33,6.69,3.5,13.38,6.99,20.06,10.52.7.37,1.17.37,1.83-.1,7.38-5.22,15.15-9.78,23.44-13.39,5.54-2.41,11.24-4.29,17.25-5.12,4.2-.58,8.41-.78,12.55.43,1.77.52,3.42,1.28,4.88,2.43,3.35,2.62,4.2,6.82,2.14,10.54-1.3,2.34-3.31,3.98-5.49,5.43-.14.1-.35.16-.52.15-3.38-.22-6.76-.46-10.18-.82,2.5-3.78,4.83-7.54,6.71-11.73-.78-.06-1.48-.13-2.17-.17-5.86-.35-11.56.66-17.26,1.88-10.67,2.29-20.41,6.86-30.02,12.07.34.21.61.39.89.56,3.69,2.17,7.31,4.45,10.22,7.64,2.65,2.9,4.22,6.27,4.3,10.25.05,2.51-.59,4.88-1.47,7.2-.07.19-.23.36-.38.49-6.14,5.06-12.29,10.12-18.44,15.17-.04.03-.09.06-.16.1ZM50.96,31.94c2.69-3.4,3.81-7.24,3.18-11.48-.74-4.93-3.59-8.42-7.95-10.65-4.11-2.1-8.59-2.56-13.12-2.72-.21,0-.47.1-.63.25-1.43,1.32-2.7,2.76-3.6,4.52-1.51,2.96-1.11,5.84,1.13,8.29,1.47,1.61,3.27,2.8,5.17,3.79,5.05,2.62,10.15,5.17,15.22,7.74.18.09.38.17.59.27Z\" fill=\"red\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> <b> Terme :<\/b> Liposuc\u00adcion, amincis\u00adse\u00adment de la graisse<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg id=\"uuid-b003a3b2-6660-4321-914e-09565e94dca5\" viewBox=\"0 0 137.04 86.98\"><path d=\"M71.97,86.98c1.14-2.65,2.32-5.23,3.36-7.86,1.14-2.86,1.96-5.81,2.37-8.89.5-3.79-.89-6.68-3.83-8.95-3.32-2.58-6.93-4.7-10.63-6.69-.19-.1-.58-.08-.75.05-3.2,2.41-6.44,4.77-9.55,7.29-1.45,1.18-2.62,2.7-3.94,4.05-2.31,2.38-4.61,4.77-6.97,7.1-3.97,3.95-8.88,6.19-14.29,7.18-8.38,1.53-15.85-.67-22.24-6.26C.11,69.29-1.51,61.47,1.49,54.62c.93-2.12,2.3-4.04,3.52-6.02.19-.3.58-.55.93-.68,5.89-2.13,11.79-4.24,17.69-6.35.07-.03.15-.04.34.07-.24.21-.48.41-.7.64-2.86,2.83-5.47,5.87-7.19,9.55-1.29,2.75-2,5.61-1.15,8.64,1,3.54,3.54,5.67,6.81,6.95,4.19,1.64,8.48,1.32,12.75.27,4.54-1.11,8.57-3.37,12.49-5.82,4.28-2.67,8.32-5.69,12.16-8.96.12-.1.26-.18.41-.29-.15-.12-.2-.17-.27-.21-8.16-4.07-16.06-8.65-24.64-11.84-2.95-1.1-5.91-2.22-8.81-3.45-1.46-.62-2.85-1.42-4.18-2.28-4.26-2.74-5.79-6.8-5.39-11.69.54-6.57,4.15-11.32,9.17-15.18,5.12-3.93,10.85-6.52,17.26-7.47,4.84-.72,9.7-.94,14.33,1.06,4.71,2.03,8.17,5.31,9.48,10.44.86,3.37.13,6.56-1.39,9.63-1.87,3.79-4.91,6.48-8.23,8.92-1.17.86-2.39,1.67-3.65,2.55.21.13.37.24.54.33,6.69,3.5,13.38,6.99,20.06,10.52.7.37,1.17.37,1.83-.1,7.38-5.22,15.15-9.78,23.44-13.39,5.54-2.41,11.24-4.29,17.25-5.12,4.2-.58,8.41-.78,12.55.43,1.77.52,3.42,1.28,4.88,2.43,3.35,2.62,4.2,6.82,2.14,10.54-1.3,2.34-3.31,3.98-5.49,5.43-.14.1-.35.16-.52.15-3.38-.22-6.76-.46-10.18-.82,2.5-3.78,4.83-7.54,6.71-11.73-.78-.06-1.48-.13-2.17-.17-5.86-.35-11.56.66-17.26,1.88-10.67,2.29-20.41,6.86-30.02,12.07.34.21.61.39.89.56,3.69,2.17,7.31,4.45,10.22,7.64,2.65,2.9,4.22,6.27,4.3,10.25.05,2.51-.59,4.88-1.47,7.2-.07.19-.23.36-.38.49-6.14,5.06-12.29,10.12-18.44,15.17-.04.03-.09.06-.16.1ZM50.96,31.94c2.69-3.4,3.81-7.24,3.18-11.48-.74-4.93-3.59-8.42-7.95-10.65-4.11-2.1-8.59-2.56-13.12-2.72-.21,0-.47.1-.63.25-1.43,1.32-2.7,2.76-3.6,4.52-1.51,2.96-1.11,5.84,1.13,8.29,1.47,1.61,3.27,2.8,5.17,3.79,5.05,2.62,10.15,5.17,15.22,7.74.18.09.38.17.59.27Z\" fill=\"red\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Type d'anesth\u00e9sie :<\/b> anesth\u00e9\u00adsie locale ou g\u00e9n\u00e9rale.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg id=\"uuid-b003a3b2-6660-4321-914e-09565e94dca5\" viewBox=\"0 0 137.04 86.98\"><path d=\"M71.97,86.98c1.14-2.65,2.32-5.23,3.36-7.86,1.14-2.86,1.96-5.81,2.37-8.89.5-3.79-.89-6.68-3.83-8.95-3.32-2.58-6.93-4.7-10.63-6.69-.19-.1-.58-.08-.75.05-3.2,2.41-6.44,4.77-9.55,7.29-1.45,1.18-2.62,2.7-3.94,4.05-2.31,2.38-4.61,4.77-6.97,7.1-3.97,3.95-8.88,6.19-14.29,7.18-8.38,1.53-15.85-.67-22.24-6.26C.11,69.29-1.51,61.47,1.49,54.62c.93-2.12,2.3-4.04,3.52-6.02.19-.3.58-.55.93-.68,5.89-2.13,11.79-4.24,17.69-6.35.07-.03.15-.04.34.07-.24.21-.48.41-.7.64-2.86,2.83-5.47,5.87-7.19,9.55-1.29,2.75-2,5.61-1.15,8.64,1,3.54,3.54,5.67,6.81,6.95,4.19,1.64,8.48,1.32,12.75.27,4.54-1.11,8.57-3.37,12.49-5.82,4.28-2.67,8.32-5.69,12.16-8.96.12-.1.26-.18.41-.29-.15-.12-.2-.17-.27-.21-8.16-4.07-16.06-8.65-24.64-11.84-2.95-1.1-5.91-2.22-8.81-3.45-1.46-.62-2.85-1.42-4.18-2.28-4.26-2.74-5.79-6.8-5.39-11.69.54-6.57,4.15-11.32,9.17-15.18,5.12-3.93,10.85-6.52,17.26-7.47,4.84-.72,9.7-.94,14.33,1.06,4.71,2.03,8.17,5.31,9.48,10.44.86,3.37.13,6.56-1.39,9.63-1.87,3.79-4.91,6.48-8.23,8.92-1.17.86-2.39,1.67-3.65,2.55.21.13.37.24.54.33,6.69,3.5,13.38,6.99,20.06,10.52.7.37,1.17.37,1.83-.1,7.38-5.22,15.15-9.78,23.44-13.39,5.54-2.41,11.24-4.29,17.25-5.12,4.2-.58,8.41-.78,12.55.43,1.77.52,3.42,1.28,4.88,2.43,3.35,2.62,4.2,6.82,2.14,10.54-1.3,2.34-3.31,3.98-5.49,5.43-.14.1-.35.16-.52.15-3.38-.22-6.76-.46-10.18-.82,2.5-3.78,4.83-7.54,6.71-11.73-.78-.06-1.48-.13-2.17-.17-5.86-.35-11.56.66-17.26,1.88-10.67,2.29-20.41,6.86-30.02,12.07.34.21.61.39.89.56,3.69,2.17,7.31,4.45,10.22,7.64,2.65,2.9,4.22,6.27,4.3,10.25.05,2.51-.59,4.88-1.47,7.2-.07.19-.23.36-.38.49-6.14,5.06-12.29,10.12-18.44,15.17-.04.03-.09.06-.16.1ZM50.96,31.94c2.69-3.4,3.81-7.24,3.18-11.48-.74-4.93-3.59-8.42-7.95-10.65-4.11-2.1-8.59-2.56-13.12-2.72-.21,0-.47.1-.63.25-1.43,1.32-2.7,2.76-3.6,4.52-1.51,2.96-1.11,5.84,1.13,8.29,1.47,1.61,3.27,2.8,5.17,3.79,5.05,2.62,10.15,5.17,15.22,7.74.18.09.38.17.59.27Z\" fill=\"red\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>S\u00e9jour en clinique : <\/b>ambula\u00adtoire ; si la mesure est tr\u00e8s importante, 1&nbsp;nuit\u00e9e<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg id=\"uuid-b003a3b2-6660-4321-914e-09565e94dca5\" viewBox=\"0 0 137.04 86.98\"><path d=\"M71.97,86.98c1.14-2.65,2.32-5.23,3.36-7.86,1.14-2.86,1.96-5.81,2.37-8.89.5-3.79-.89-6.68-3.83-8.95-3.32-2.58-6.93-4.7-10.63-6.69-.19-.1-.58-.08-.75.05-3.2,2.41-6.44,4.77-9.55,7.29-1.45,1.18-2.62,2.7-3.94,4.05-2.31,2.38-4.61,4.77-6.97,7.1-3.97,3.95-8.88,6.19-14.29,7.18-8.38,1.53-15.85-.67-22.24-6.26C.11,69.29-1.51,61.47,1.49,54.62c.93-2.12,2.3-4.04,3.52-6.02.19-.3.58-.55.93-.68,5.89-2.13,11.79-4.24,17.69-6.35.07-.03.15-.04.34.07-.24.21-.48.41-.7.64-2.86,2.83-5.47,5.87-7.19,9.55-1.29,2.75-2,5.61-1.15,8.64,1,3.54,3.54,5.67,6.81,6.95,4.19,1.64,8.48,1.32,12.75.27,4.54-1.11,8.57-3.37,12.49-5.82,4.28-2.67,8.32-5.69,12.16-8.96.12-.1.26-.18.41-.29-.15-.12-.2-.17-.27-.21-8.16-4.07-16.06-8.65-24.64-11.84-2.95-1.1-5.91-2.22-8.81-3.45-1.46-.62-2.85-1.42-4.18-2.28-4.26-2.74-5.79-6.8-5.39-11.69.54-6.57,4.15-11.32,9.17-15.18,5.12-3.93,10.85-6.52,17.26-7.47,4.84-.72,9.7-.94,14.33,1.06,4.71,2.03,8.17,5.31,9.48,10.44.86,3.37.13,6.56-1.39,9.63-1.87,3.79-4.91,6.48-8.23,8.92-1.17.86-2.39,1.67-3.65,2.55.21.13.37.24.54.33,6.69,3.5,13.38,6.99,20.06,10.52.7.37,1.17.37,1.83-.1,7.38-5.22,15.15-9.78,23.44-13.39,5.54-2.41,11.24-4.29,17.25-5.12,4.2-.58,8.41-.78,12.55.43,1.77.52,3.42,1.28,4.88,2.43,3.35,2.62,4.2,6.82,2.14,10.54-1.3,2.34-3.31,3.98-5.49,5.43-.14.1-.35.16-.52.15-3.38-.22-6.76-.46-10.18-.82,2.5-3.78,4.83-7.54,6.71-11.73-.78-.06-1.48-.13-2.17-.17-5.86-.35-11.56.66-17.26,1.88-10.67,2.29-20.41,6.86-30.02,12.07.34.21.61.39.89.56,3.69,2.17,7.31,4.45,10.22,7.64,2.65,2.9,4.22,6.27,4.3,10.25.05,2.51-.59,4.88-1.47,7.2-.07.19-.23.36-.38.49-6.14,5.06-12.29,10.12-18.44,15.17-.04.03-.09.06-.16.1ZM50.96,31.94c2.69-3.4,3.81-7.24,3.18-11.48-.74-4.93-3.59-8.42-7.95-10.65-4.11-2.1-8.59-2.56-13.12-2.72-.21,0-.47.1-.63.25-1.43,1.32-2.7,2.76-3.6,4.52-1.51,2.96-1.11,5.84,1.13,8.29,1.47,1.61,3.27,2.8,5.17,3.79,5.05,2.62,10.15,5.17,15.22,7.74.18.09.38.17.59.27Z\" fill=\"red\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Traite\u00adment postop\u00e9\u00adra\u00adtoire : <\/b>v\u00eatements de compres\u00adsion (gaine\/\u200bpantalon) pendant 6&nbsp;semaines<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg id=\"uuid-b003a3b2-6660-4321-914e-09565e94dca5\" viewBox=\"0 0 137.04 86.98\"><path d=\"M71.97,86.98c1.14-2.65,2.32-5.23,3.36-7.86,1.14-2.86,1.96-5.81,2.37-8.89.5-3.79-.89-6.68-3.83-8.95-3.32-2.58-6.93-4.7-10.63-6.69-.19-.1-.58-.08-.75.05-3.2,2.41-6.44,4.77-9.55,7.29-1.45,1.18-2.62,2.7-3.94,4.05-2.31,2.38-4.61,4.77-6.97,7.1-3.97,3.95-8.88,6.19-14.29,7.18-8.38,1.53-15.85-.67-22.24-6.26C.11,69.29-1.51,61.47,1.49,54.62c.93-2.12,2.3-4.04,3.52-6.02.19-.3.58-.55.93-.68,5.89-2.13,11.79-4.24,17.69-6.35.07-.03.15-.04.34.07-.24.21-.48.41-.7.64-2.86,2.83-5.47,5.87-7.19,9.55-1.29,2.75-2,5.61-1.15,8.64,1,3.54,3.54,5.67,6.81,6.95,4.19,1.64,8.48,1.32,12.75.27,4.54-1.11,8.57-3.37,12.49-5.82,4.28-2.67,8.32-5.69,12.16-8.96.12-.1.26-.18.41-.29-.15-.12-.2-.17-.27-.21-8.16-4.07-16.06-8.65-24.64-11.84-2.95-1.1-5.91-2.22-8.81-3.45-1.46-.62-2.85-1.42-4.18-2.28-4.26-2.74-5.79-6.8-5.39-11.69.54-6.57,4.15-11.32,9.17-15.18,5.12-3.93,10.85-6.52,17.26-7.47,4.84-.72,9.7-.94,14.33,1.06,4.71,2.03,8.17,5.31,9.48,10.44.86,3.37.13,6.56-1.39,9.63-1.87,3.79-4.91,6.48-8.23,8.92-1.17.86-2.39,1.67-3.65,2.55.21.13.37.24.54.33,6.69,3.5,13.38,6.99,20.06,10.52.7.37,1.17.37,1.83-.1,7.38-5.22,15.15-9.78,23.44-13.39,5.54-2.41,11.24-4.29,17.25-5.12,4.2-.58,8.41-.78,12.55.43,1.77.52,3.42,1.28,4.88,2.43,3.35,2.62,4.2,6.82,2.14,10.54-1.3,2.34-3.31,3.98-5.49,5.43-.14.1-.35.16-.52.15-3.38-.22-6.76-.46-10.18-.82,2.5-3.78,4.83-7.54,6.71-11.73-.78-.06-1.48-.13-2.17-.17-5.86-.35-11.56.66-17.26,1.88-10.67,2.29-20.41,6.86-30.02,12.07.34.21.61.39.89.56,3.69,2.17,7.31,4.45,10.22,7.64,2.65,2.9,4.22,6.27,4.3,10.25.05,2.51-.59,4.88-1.47,7.2-.07.19-.23.36-.38.49-6.14,5.06-12.29,10.12-18.44,15.17-.04.03-.09.06-.16.1ZM50.96,31.94c2.69-3.4,3.81-7.24,3.18-11.48-.74-4.93-3.59-8.42-7.95-10.65-4.11-2.1-8.59-2.56-13.12-2.72-.21,0-.47.1-.63.25-1.43,1.32-2.7,2.76-3.6,4.52-1.51,2.96-1.11,5.84,1.13,8.29,1.47,1.61,3.27,2.8,5.17,3.79,5.05,2.62,10.15,5.17,15.22,7.74.18.09.38.17.59.27Z\" fill=\"red\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Apte \u00e0&nbsp;la vie en soci\u00e9t\u00e9 : <\/b>apr\u00e8s 3-5 jours (selon l'\u00e9tendue)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg id=\"uuid-b003a3b2-6660-4321-914e-09565e94dca5\" viewBox=\"0 0 137.04 86.98\"><path d=\"M71.97,86.98c1.14-2.65,2.32-5.23,3.36-7.86,1.14-2.86,1.96-5.81,2.37-8.89.5-3.79-.89-6.68-3.83-8.95-3.32-2.58-6.93-4.7-10.63-6.69-.19-.1-.58-.08-.75.05-3.2,2.41-6.44,4.77-9.55,7.29-1.45,1.18-2.62,2.7-3.94,4.05-2.31,2.38-4.61,4.77-6.97,7.1-3.97,3.95-8.88,6.19-14.29,7.18-8.38,1.53-15.85-.67-22.24-6.26C.11,69.29-1.51,61.47,1.49,54.62c.93-2.12,2.3-4.04,3.52-6.02.19-.3.58-.55.93-.68,5.89-2.13,11.79-4.24,17.69-6.35.07-.03.15-.04.34.07-.24.21-.48.41-.7.64-2.86,2.83-5.47,5.87-7.19,9.55-1.29,2.75-2,5.61-1.15,8.64,1,3.54,3.54,5.67,6.81,6.95,4.19,1.64,8.48,1.32,12.75.27,4.54-1.11,8.57-3.37,12.49-5.82,4.28-2.67,8.32-5.69,12.16-8.96.12-.1.26-.18.41-.29-.15-.12-.2-.17-.27-.21-8.16-4.07-16.06-8.65-24.64-11.84-2.95-1.1-5.91-2.22-8.81-3.45-1.46-.62-2.85-1.42-4.18-2.28-4.26-2.74-5.79-6.8-5.39-11.69.54-6.57,4.15-11.32,9.17-15.18,5.12-3.93,10.85-6.52,17.26-7.47,4.84-.72,9.7-.94,14.33,1.06,4.71,2.03,8.17,5.31,9.48,10.44.86,3.37.13,6.56-1.39,9.63-1.87,3.79-4.91,6.48-8.23,8.92-1.17.86-2.39,1.67-3.65,2.55.21.13.37.24.54.33,6.69,3.5,13.38,6.99,20.06,10.52.7.37,1.17.37,1.83-.1,7.38-5.22,15.15-9.78,23.44-13.39,5.54-2.41,11.24-4.29,17.25-5.12,4.2-.58,8.41-.78,12.55.43,1.77.52,3.42,1.28,4.88,2.43,3.35,2.62,4.2,6.82,2.14,10.54-1.3,2.34-3.31,3.98-5.49,5.43-.14.1-.35.16-.52.15-3.38-.22-6.76-.46-10.18-.82,2.5-3.78,4.83-7.54,6.71-11.73-.78-.06-1.48-.13-2.17-.17-5.86-.35-11.56.66-17.26,1.88-10.67,2.29-20.41,6.86-30.02,12.07.34.21.61.39.89.56,3.69,2.17,7.31,4.45,10.22,7.64,2.65,2.9,4.22,6.27,4.3,10.25.05,2.51-.59,4.88-1.47,7.2-.07.19-.23.36-.38.49-6.14,5.06-12.29,10.12-18.44,15.17-.04.03-.09.06-.16.1ZM50.96,31.94c2.69-3.4,3.81-7.24,3.18-11.48-.74-4.93-3.59-8.42-7.95-10.65-4.11-2.1-8.59-2.56-13.12-2.72-.21,0-.47.1-.63.25-1.43,1.32-2.7,2.76-3.6,4.52-1.51,2.96-1.11,5.84,1.13,8.29,1.47,1.61,3.27,2.8,5.17,3.79,5.05,2.62,10.15,5.17,15.22,7.74.18.09.38.17.59.27Z\" fill=\"red\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Travaillable : <\/b>apr\u00e8s environ 3-10 jours (selon l'effort physique)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg id=\"uuid-b003a3b2-6660-4321-914e-09565e94dca5\" viewBox=\"0 0 137.04 86.98\"><path d=\"M71.97,86.98c1.14-2.65,2.32-5.23,3.36-7.86,1.14-2.86,1.96-5.81,2.37-8.89.5-3.79-.89-6.68-3.83-8.95-3.32-2.58-6.93-4.7-10.63-6.69-.19-.1-.58-.08-.75.05-3.2,2.41-6.44,4.77-9.55,7.29-1.45,1.18-2.62,2.7-3.94,4.05-2.31,2.38-4.61,4.77-6.97,7.1-3.97,3.95-8.88,6.19-14.29,7.18-8.38,1.53-15.85-.67-22.24-6.26C.11,69.29-1.51,61.47,1.49,54.62c.93-2.12,2.3-4.04,3.52-6.02.19-.3.58-.55.93-.68,5.89-2.13,11.79-4.24,17.69-6.35.07-.03.15-.04.34.07-.24.21-.48.41-.7.64-2.86,2.83-5.47,5.87-7.19,9.55-1.29,2.75-2,5.61-1.15,8.64,1,3.54,3.54,5.67,6.81,6.95,4.19,1.64,8.48,1.32,12.75.27,4.54-1.11,8.57-3.37,12.49-5.82,4.28-2.67,8.32-5.69,12.16-8.96.12-.1.26-.18.41-.29-.15-.12-.2-.17-.27-.21-8.16-4.07-16.06-8.65-24.64-11.84-2.95-1.1-5.91-2.22-8.81-3.45-1.46-.62-2.85-1.42-4.18-2.28-4.26-2.74-5.79-6.8-5.39-11.69.54-6.57,4.15-11.32,9.17-15.18,5.12-3.93,10.85-6.52,17.26-7.47,4.84-.72,9.7-.94,14.33,1.06,4.71,2.03,8.17,5.31,9.48,10.44.86,3.37.13,6.56-1.39,9.63-1.87,3.79-4.91,6.48-8.23,8.92-1.17.86-2.39,1.67-3.65,2.55.21.13.37.24.54.33,6.69,3.5,13.38,6.99,20.06,10.52.7.37,1.17.37,1.83-.1,7.38-5.22,15.15-9.78,23.44-13.39,5.54-2.41,11.24-4.29,17.25-5.12,4.2-.58,8.41-.78,12.55.43,1.77.52,3.42,1.28,4.88,2.43,3.35,2.62,4.2,6.82,2.14,10.54-1.3,2.34-3.31,3.98-5.49,5.43-.14.1-.35.16-.52.15-3.38-.22-6.76-.46-10.18-.82,2.5-3.78,4.83-7.54,6.71-11.73-.78-.06-1.48-.13-2.17-.17-5.86-.35-11.56.66-17.26,1.88-10.67,2.29-20.41,6.86-30.02,12.07.34.21.61.39.89.56,3.69,2.17,7.31,4.45,10.22,7.64,2.65,2.9,4.22,6.27,4.3,10.25.05,2.51-.59,4.88-1.47,7.2-.07.19-.23.36-.38.49-6.14,5.06-12.29,10.12-18.44,15.17-.04.03-.09.06-.16.1ZM50.96,31.94c2.69-3.4,3.81-7.24,3.18-11.48-.74-4.93-3.59-8.42-7.95-10.65-4.11-2.1-8.59-2.56-13.12-2.72-.21,0-.47.1-.63.25-1.43,1.32-2.7,2.76-3.6,4.52-1.51,2.96-1.11,5.84,1.13,8.29,1.47,1.61,3.27,2.8,5.17,3.79,5.05,2.62,10.15,5.17,15.22,7.74.18.09.38.17.59.27Z\" fill=\"red\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Co\u00fbt : <\/b>\u00e0&nbsp;partir de 5000,-&nbsp;CHF<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad30447 elementor-align-center animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"ad30447\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontaktformular\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demandez mainten\u00adant<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b7b455 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b7b455\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3480a0\" data-id=\"d3480a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd441a2 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"bd441a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg id=\"uuid-b003a3b2-6660-4321-914e-09565e94dca5\" viewBox=\"0 0 137.04 86.98\"><path d=\"M71.97,86.98c1.14-2.65,2.32-5.23,3.36-7.86,1.14-2.86,1.96-5.81,2.37-8.89.5-3.79-.89-6.68-3.83-8.95-3.32-2.58-6.93-4.7-10.63-6.69-.19-.1-.58-.08-.75.05-3.2,2.41-6.44,4.77-9.55,7.29-1.45,1.18-2.62,2.7-3.94,4.05-2.31,2.38-4.61,4.77-6.97,7.1-3.97,3.95-8.88,6.19-14.29,7.18-8.38,1.53-15.85-.67-22.24-6.26C.11,69.29-1.51,61.47,1.49,54.62c.93-2.12,2.3-4.04,3.52-6.02.19-.3.58-.55.93-.68,5.89-2.13,11.79-4.24,17.69-6.35.07-.03.15-.04.34.07-.24.21-.48.41-.7.64-2.86,2.83-5.47,5.87-7.19,9.55-1.29,2.75-2,5.61-1.15,8.64,1,3.54,3.54,5.67,6.81,6.95,4.19,1.64,8.48,1.32,12.75.27,4.54-1.11,8.57-3.37,12.49-5.82,4.28-2.67,8.32-5.69,12.16-8.96.12-.1.26-.18.41-.29-.15-.12-.2-.17-.27-.21-8.16-4.07-16.06-8.65-24.64-11.84-2.95-1.1-5.91-2.22-8.81-3.45-1.46-.62-2.85-1.42-4.18-2.28-4.26-2.74-5.79-6.8-5.39-11.69.54-6.57,4.15-11.32,9.17-15.18,5.12-3.93,10.85-6.52,17.26-7.47,4.84-.72,9.7-.94,14.33,1.06,4.71,2.03,8.17,5.31,9.48,10.44.86,3.37.13,6.56-1.39,9.63-1.87,3.79-4.91,6.48-8.23,8.92-1.17.86-2.39,1.67-3.65,2.55.21.13.37.24.54.33,6.69,3.5,13.38,6.99,20.06,10.52.7.37,1.17.37,1.83-.1,7.38-5.22,15.15-9.78,23.44-13.39,5.54-2.41,11.24-4.29,17.25-5.12,4.2-.58,8.41-.78,12.55.43,1.77.52,3.42,1.28,4.88,2.43,3.35,2.62,4.2,6.82,2.14,10.54-1.3,2.34-3.31,3.98-5.49,5.43-.14.1-.35.16-.52.15-3.38-.22-6.76-.46-10.18-.82,2.5-3.78,4.83-7.54,6.71-11.73-.78-.06-1.48-.13-2.17-.17-5.86-.35-11.56.66-17.26,1.88-10.67,2.29-20.41,6.86-30.02,12.07.34.21.61.39.89.56,3.69,2.17,7.31,4.45,10.22,7.64,2.65,2.9,4.22,6.27,4.3,10.25.05,2.51-.59,4.88-1.47,7.2-.07.19-.23.36-.38.49-6.14,5.06-12.29,10.12-18.44,15.17-.04.03-.09.06-.16.1ZM50.96,31.94c2.69-3.4,3.81-7.24,3.18-11.48-.74-4.93-3.59-8.42-7.95-10.65-4.11-2.1-8.59-2.56-13.12-2.72-.21,0-.47.1-.63.25-1.43,1.32-2.7,2.76-3.6,4.52-1.51,2.96-1.11,5.84,1.13,8.29,1.47,1.61,3.27,2.8,5.17,3.79,5.05,2.62,10.15,5.17,15.22,7.74.18.09.38.17.59.27Z\" fill=\"red\" \/><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99b945e animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"99b945e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plus de d\u00e9tails sur la liposuccion<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c14be1c elementor-widget elementor-widget-jet-accordion\" data-id=\"c14be1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;content_scrolling&quot;:&quot;yes&quot;,&quot;content_scrolling_offset&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;content_scrolling_offset_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;content_scrolling_offset_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;content_scrolling_delay&quot;:500}\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:true,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:true,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;switchScrollingOffsetTablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;switchScrollingOffsetMobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-2021\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-2021\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Histo\u00adri\u00adque<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-2021\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>La m\u00e9thode a&nbsp;\u00e9t\u00e9 d\u00e9velo\u00adp\u00adp\u00e9e dans les ann\u00e9es 70 par <strong>Georgio Fischer \u00e0&nbsp;Rome<\/strong>, Pierre Fournier et Yves Illouz \u00e0&nbsp;Paris. Mais la m\u00e9thode n'a \u00e9t\u00e9 largement diffus\u00e9e qu'apr\u00e8s l'introduction de la technique dite \"humide\", c'est-\u00e0-dire l'aspiration apr\u00e8s injection de solution saline \u00e0&nbsp;la fin des ann\u00e9es 80. Nous <strong>avons \u00e9t\u00e9 parmi les premiers \u00e0<\/strong> observer et \u00e0&nbsp;nous appro\u00adprier person\u00adnel\u00adle\u00adment la m\u00e9thode de ces enseig\u00adnants innovants lors de stages d'observation.  <\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-2022\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-2022\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">D\u00e9rou\u00adle\u00adment d'une liposuccion<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-2022\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Lors d'une liposuc\u00adcion, les <strong>zones probl\u00e9\u00adma\u00adti\u00adques qui le g\u00eanent<\/strong> sont d'abord discut\u00e9es avec le patient et la proc\u00e9dure est expliqu\u00e9e en d\u00e9tail. Avant l'op\u00e9ration, les r\u00e9gions \u00e0&nbsp;traiter sont<strong> marqu\u00e9es avec pr\u00e9cision<\/strong>, comme sur une carte d'altitude. La r\u00e9gion marqu\u00e9e est ensuite infiltr\u00e9e avec une solution dite \"tumes\u00adcente\" : Le tissu adipeux sous-cutan\u00e9 est rempli de mani\u00e8re uniforme \u00e0&nbsp;l'aide d'un syst\u00e8me d'infiltration sp\u00e9cial comportant de nombreu\u00adses <strong>canules tr\u00e8s fines<\/strong>.    <\/p>\n<p>Ce processus s'effectue norma\u00adle\u00adment <strong>en pr\u00e9sence d'un anesth\u00e9\u00adsiste<\/strong>, dans ce que l'on appelle <strong>une somno\u00adlence<\/strong>, de sorte que ce processus de remplis\u00adsage, qui cr\u00e9e une certaine pression dans les tissus et peut donc \u00eatre d\u00e9sag\u00adr\u00e9a\u00adble pour le patient, n'est pas per\u00e7u. La solution tumes\u00adcente contient entre autres un <strong>anesth\u00e9\u00adsi\u00adant local<\/strong> et, une fois qu'elle s'est r\u00e9partie unifor\u00adm\u00e9\u00adment dans la r\u00e9gion \u00e0&nbsp;traiter, <strong>la douleur est totale\u00adment supprim\u00e9e<\/strong>, de sorte que la somno\u00adlence peut \u00eatre r\u00e9activ\u00e9e. L'absence d'anesth\u00e9sie permet au patient de parti\u00adci\u00adper active\u00adment \u00e0&nbsp;l'op\u00e9ration (par exemple, lors de l'aspiration de la culotte de cheval ou de la r\u00e9gion fessi\u00e8re, il peut se tourner lui-m\u00eame sur la table d'op\u00e9ration, soulever sa jambe, etc.), ce qui facilite consid\u00e9\u00adra\u00adblem\u00adent le travail du chirur\u00adgien et lui permet d'\u00e9valuer l'effet de la gravit\u00e9 et du mouvement muscu\u00adlaire pendant l'intervention. Cette technique permet d'obtenir un <strong>r\u00e9sultat naturel et durable<\/strong>. Si vous le souhaitez, vous pouvez bien s\u00fbr opter pour une <strong>anesth\u00e9\u00adsie g\u00e9n\u00e9rale<\/strong>.    <\/p>\n<p>L'aspiration propre\u00adment dite s'effectue ensuite en intro\u00addui\u00adsant une canule de liposuc\u00adcion par<strong> de tr\u00e8s petites incisions cutan\u00e9es<\/strong> et en <strong>d\u00e9tachant m\u00e9cani\u00adquement<\/strong> le <strong>tissu adipeux<\/strong> \u00e0&nbsp;enlever \u00e0&nbsp;l'aide de cette canule, ce qui permet de former plusieurs struc\u00adtures en grille super\u00adpo\u00ads\u00e9es<u>(technique du criss-cross<\/u>). Gr\u00e2ce \u00e0&nbsp;la solution inject\u00e9e, la structure du tissu adipeux est rel\u00e2ch\u00e9e et les diff\u00e9\u00adren\u00adtes cellules grais\u00adseu\u00adses peuvent \u00eatre plus facile\u00adment d\u00e9tach\u00e9es de leur gangue. En outre, la structure l\u00e2che du tissu permet aux nerfs et aux vaisseaux d'\u00e9viter les mouve\u00adments de la canule, ce qui<strong> limite le risque de blessure<\/strong> pour les struc\u00adtures plus importan\u00adtes. Nous utilisons princi\u00adpa\u00adle\u00adment la technique moderne de la \"<u>canule vibrante<\/u>\" (la pointe de la canule et les orifices qui s'y trouvent sont d\u00e9plac\u00e9s tr\u00e8s rapide\u00adment d'avant en arri\u00e8re par un moteur, ce qui permet une extra\u00adc\u00adtion parti\u00adcu\u00adli\u00e8\u00adre\u00adment douce des cellules grais\u00adseu\u00adses). Des canules parti\u00adcu\u00adli\u00e8\u00adre\u00adment fines sont utilis\u00e9es \u00e0&nbsp;proximit\u00e9 de la surface de la peau, ce qui permet d'\u00e9viter la formation de vagues ou de bosses sur la peau, contrai\u00adre\u00adment aux m\u00e9thodes pr\u00e9c\u00e9\u00adden\u00adtes.<u>(Technique de tunnel\u00adi\u00adsa\u00adtion fine<\/u>)   <\/p>\n<p>Gr\u00e2ce \u00e0&nbsp;une <strong>m\u00e9thode de travail sensible et tr\u00e8s diff\u00e9\u00adren\u00adci\u00e9e<\/strong> et \u00e0&nbsp;un modelage optimal pr\u00e9ser\u00advant au maximum les nerfs et les vaisseaux, il est ainsi possible de redes\u00adsi\u00adner la silhou\u00adette du corps. L'exp\u00e9rience appro\u00adfon\u00addie et le sens esth\u00e9\u00adtique du chirur\u00adgien sont ici indis\u00adpens\u00adables pour obtenir des propor\u00adti\u00adons harmo\u00adnieu\u00adses avec des lignes naturel\u00adles, sans toutefois aller au-del\u00e0 de la mesure m\u00e9dicale raisonnable.&nbsp;<\/p>\n<p>Il est \u00e9galement possible de <strong>remplir de graisse les tissus pr\u00e9lev\u00e9s \u00e0&nbsp;d'autres endroits du corps<\/strong> (\"lipos\u00adculp\u00adture \/ lipop\u00adlas\u00adtie\"). Le tissu adipeux retir\u00e9 est utilis\u00e9 pour am\u00e9liorer le contour du corps et combler certaines zones. Chez les femmes, l'injection est souvent pratiqu\u00e9e<strong> au niveau<\/strong> des<strong> seins ou des fesses<\/strong>. Chez les hommes, l'injection se fait \u00e9galement dans <strong>la r\u00e9gion des fesses ou des pectoraux<\/strong>.   <\/p>\n<p>Gr\u00e2ce \u00e0&nbsp;une nouvelle technique encore plus pointue (\"lipos\u00adculp\u00adture haute d\u00e9fini\u00adtion\"), les <strong>contours de l'abdomen et des bras<\/strong> peuvent \u00eatre <strong>model\u00e9s selon vos souhaits<\/strong>. Il est ainsi possible d'obtenir des contours plus souples et plus f\u00e9minins chez les femmes et une image plus muscl\u00e9e et athl\u00e9\u00adtique chez les&nbsp;hommes.&nbsp;<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-2023\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-2023\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Soins postop\u00e9\u00adra\u00adtoires et cicatri\u00adsa\u00adtion des&nbsp;plaies<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-2023\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><div>Cette inter\u00adven\u00adtion est g\u00e9n\u00e9ra\u00adle\u00adment r\u00e9alis\u00e9e <strong>en ambula\u00adtoire<\/strong>, mais si l'intervention est plus importante, un s\u00e9jour d'une nuit \u00e0&nbsp;l'h\u00f4pital peut \u00eatre r\u00e9serv\u00e9, en parti\u00adcu\u00adlier si le patient vit seul ou s'il n'y a&nbsp;pas de surveil\u00adlance le premier jour apr\u00e8s l'op\u00e9ration. Imm\u00e9dia\u00adte\u00adment apr\u00e8s l'intervention, le patient enfile une <strong>  pantalons\/\u200bgaines de compres\u00adsion sp\u00e9ciaux <\/strong>  qui comprime unifor\u00adm\u00e9\u00adment la zone de la plaie trait\u00e9e, contri\u00adbuant ainsi \u00e0&nbsp;une cicatri\u00adsa\u00adtion&nbsp;rapide.&nbsp;\n<p>Il n'y a&nbsp;<strong>pas de douleur importante<\/strong> apr\u00e8s l'intervention, un gonfle\u00adment initial de la plaie dispara\u00eet tr\u00e8s rapide\u00adment apr\u00e8s deux ou trois jours, les ecchy\u00admo\u00adses discr\u00e8tes se r\u00e9sorbent \u00e9galement en peu de temps. Il <strong>est conseill\u00e9 de se reposer pendant quelques jours<\/strong> et d'\u00e9viter les sports de comp\u00e9\u00adti\u00adtion pendant les premi\u00e8res semaines suivant l'intervention, mais le r\u00e9sultat souhait\u00e9 est d\u00e9j\u00e0 visible apr\u00e8s environ trois semaines - m\u00eame si d'autres processus de r\u00e9para\u00adtion se d\u00e9roulent en profon\u00addeur dans les tissus, qui peuvent finale\u00adment durer jusqu'\u00e0 trois mois, mais ne sont plus percep\u00adti\u00adbles pour le patient.&nbsp;<\/p><\/div>\n<div>M\u00eame en cas d'accumulation importante de graisse, <strong>d'autres inter\u00adven\u00adti\u00adons chirur\u00adgi\u00adcales de raffer\u00admis\u00adse\u00adment<\/strong> ne sont n\u00e9ces\u00adsaires <strong>que dans des cas excep\u00adti\u00adon\u00adnels<\/strong>.<\/div>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-2024\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"4\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-2024\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Risques de la liposuccion<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-2024\" class=\"jet-toggle__content\" data-toggle=\"4\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p><strong>Des bleus discrets<\/strong> apparais\u00adsent souvent et parfois une <strong>sensation d'engourdissement<\/strong> dans les r\u00e9gions trait\u00e9es. Ces deux ph\u00e9nom\u00e8\u00adnes dispa\u00adrais\u00adsent dans les 1&nbsp;\u00e0 2&nbsp;semaines suivant l'intervention. Les points d'insertion des canules gu\u00e9ris\u00adsent g\u00e9n\u00e9ra\u00adle\u00adment <strong>sans laisser de cicatri\u00adces<\/strong>, mais il peut y&nbsp;avoir une petite <strong>cicatrice pigment\u00e9e<\/strong>, selon la peau du&nbsp;sujet.&nbsp;<\/p>\n<p>Nous avons plus de 30 ans d'exp\u00e9rience et les risques d'irr\u00e9gularit\u00e9s, d'ondulations ou de bosses sont extr\u00ea\u00adme\u00adment faibles. Pour \u00e9viter les infec\u00adtions, nous adminis\u00adtrons toujours une antibio\u00adth\u00e9\u00adra\u00adpie \"single shot\" avant l'op\u00e9ration. Ainsi, nous n'avons heureu\u00adse\u00adment jamais eu <strong>de compli\u00adca\u00adti\u00adons graves<\/strong> avec cette m\u00e9thode.&nbsp;<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-2025\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"5\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-2025\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Co\u00fbts<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-2025\" class=\"jet-toggle__content\" data-toggle=\"5\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Le co\u00fbt d'une liposuc\u00adcion se compose des frais d'utilisation de la salle d'op\u00e9ration, des honorai\u00adres de l'anesth\u00e9siste, des assistants et du personnel infirmier, des consom\u00adma\u00adbles, de la gaine de compres\u00adsion et des honorai\u00adres du chirurgien.<\/p>\n<p>Dans le cadre d'une consul\u00adta\u00adtion indivi\u00addu\u00adelle, nous souhai\u00adtons vous pr\u00e9senter sans engage\u00adment les possi\u00adbi\u00adli\u00adt\u00e9s qui vous int\u00e9res\u00adsent et \u00e9tablir un calcul exact des co\u00fbts. Vous saurez ainsi exacte\u00adment et de mani\u00e8re fiable avec quel co\u00fbt vous devez calculer.&nbsp;<\/p>\n<h3>Prix d'une liposuc\u00adcion, lipoaspiration<\/h3>\n<p>\u00e0 partir d'environ 5000,-&nbsp;CHF<\/p>\n<div>Les caisses d'assurance maladie <b>ne prennent pas en charge l'application<\/b>, car il s'agit d'un traite\u00adment esth\u00e9\u00adtique souhait\u00e9.<\/div>\n<p>Le co\u00fbt d'une <b>premi\u00e8re consul\u00adta\u00adtion sur place<\/b> est de 250,- CHF. Ce montant peut \u00eatre d\u00e9duit de votre traite\u00adment si celui-ci a&nbsp;lieu <b>dans les 6&nbsp;mois<\/b>. Si vous <b>ne vous pr\u00e9sentez pas<\/b> au premier rendez-vous fix\u00e9 de mani\u00e8re ferme, <b>des frais d'annulation de<\/b> 150,- CHF vous seront <b>factur\u00e9s<\/b>.  <\/p>\n<p><strong>Pour les rendez-vous op\u00e9ra\u00adtoires convenus, la r\u00e8gle suivante s'applique :<\/strong> en cas d'op\u00e9rations plani\u00adfi\u00e9es et dont la date est fix\u00e9e, il est souvent impos\u00adsi\u00adble pour Medicine&amp;Beauty SA de proposer un patient de rempla\u00adce\u00adment en cas d'annulation. En raison de ces diffi\u00adcul\u00adt\u00e9s de plani\u00adfi\u00adca\u00adtion, l'annulation gratuite d'un rendez-vous pour une op\u00e9ration n'est possible que si elle est effectu\u00e9e par \u00e9crit au moins 7&nbsp;jours (jours calend\u00adai\u00adres) \u00e0&nbsp;l'avance par le client par e-mail ou Whatsapp.&nbsp;<\/p>\n<p>En cas d'annulation moins de 7&nbsp;jours civils avant l'op\u00e9ration pr\u00e9vue, le client sera factur\u00e9 \u00e0&nbsp;hauteur de 50% des frais d'op\u00e9ration convenus pr\u00e9c\u00e9\u00addem\u00adment. Les rendez-vous annul\u00e9s par Medicine&amp;Beauty SA pour des raisons de sant\u00e9, m\u00e9dicales ou techni\u00adques ne peuvent pas \u00eatre rembour\u00ads\u00e9s ou indem\u00adni\u00ads\u00e9s. <strong>Un autre rendez-vous sera propos\u00e9 sans frais suppl\u00e9\u00admen\u00adtai\u00adres<\/strong>. <\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Liposuc\u00adcion Infor\u00adma\u00adti\u00adons sur la liposuc\u00adcion Bien que l'on puisse et doive influen\u00adcer consid\u00e9\u00adra\u00adblem\u00adent sa silhou\u00adette par l'alimentation et le sport, il existe des zones \u00e0&nbsp;probl\u00e8mes typiques qui ne peuvent \u00eatre suffi\u00adsam\u00adment influen\u00adc\u00e9es ni par des mesures di\u00e9t\u00e9\u00adti\u00adques, ni par un entra\u00ee\u00adne\u00adment intensif. (par exemple : taille\/\u200b\u200bhanches, int\u00e9rieur des cuisses, fesses, ventre, culotte de cheval, int\u00e9rieur&nbsp;[\u2026]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"class_list":["post-3318","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/medicine-beauty.ch\/fr\/wp-json\/wp\/v2\/pages\/3318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medicine-beauty.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/medicine-beauty.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/medicine-beauty.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medicine-beauty.ch\/fr\/wp-json\/wp\/v2\/comments?post=3318"}],"version-history":[{"count":2,"href":"https:\/\/medicine-beauty.ch\/fr\/wp-json\/wp\/v2\/pages\/3318\/revisions"}],"predecessor-version":[{"id":3932,"href":"https:\/\/medicine-beauty.ch\/fr\/wp-json\/wp\/v2\/pages\/3318\/revisions\/3932"}],"wp:attachment":[{"href":"https:\/\/medicine-beauty.ch\/fr\/wp-json\/wp\/v2\/media?parent=3318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}